{"id":131731,"date":"2026-09-01T18:36:16","date_gmt":"2026-09-01T18:36:16","guid":{"rendered":"https:\/\/newsfortnite.com\/index.php\/2026\/09\/01\/srinagar-ghost-mall-turns-into-rs-422cr-jewel-in-auction\/"},"modified":"2026-09-01T18:36:16","modified_gmt":"2026-09-01T18:36:16","slug":"srinagar-ghost-mall-turns-into-rs-422cr-jewel-in-auction","status":"publish","type":"post","link":"https:\/\/newsfortnite.com\/index.php\/2026\/09\/01\/srinagar-ghost-mall-turns-into-rs-422cr-jewel-in-auction\/","title":{"rendered":"Srinagar ghost mall turns into Rs 422cr jewel in auction"},"content":{"rendered":"<p>Post Content<\/p>","protected":false},"excerpt":{"rendered":"<p>Post Content<\/p>\n","protected":false},"author":0,"featured_media":131732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/newsfortnite.com\/index.php\/wp-json\/wp\/v2\/posts\/131731"}],"collection":[{"href":"https:\/\/newsfortnite.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsfortnite.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/newsfortnite.com\/index.php\/wp-json\/wp\/v2\/comments?post=131731"}],"version-history":[{"count":0,"href":"https:\/\/newsfortnite.com\/index.php\/wp-json\/wp\/v2\/posts\/131731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsfortnite.com\/index.php\/wp-json\/wp\/v2\/media\/131732"}],"wp:attachment":[{"href":"https:\/\/newsfortnite.com\/index.php\/wp-json\/wp\/v2\/media?parent=131731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsfortnite.com\/index.php\/wp-json\/wp\/v2\/categories?post=131731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsfortnite.com\/index.php\/wp-json\/wp\/v2\/tags?post=131731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}